{"id":8803,"date":"2017-06-25T07:41:23","date_gmt":"2017-06-25T05:41:23","guid":{"rendered":"http:\/\/in-the-focus.com\/?p=8803"},"modified":"2017-06-25T07:42:27","modified_gmt":"2017-06-25T05:42:27","slug":"araber-im-fernsehen-die-fohlenmutter","status":"publish","type":"post","link":"https:\/\/in-the-focus.com\/en\/2017\/06\/araber-im-fernsehen-die-fohlenmutter\/","title":{"rendered":"Araber im Fernsehen &#8211; &#8220;Die Fohlenmutter&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/in-the-focus.com\/wp-content\/uploads\/2017\/06\/Inge-Friedmann.jpg\" alt=\"Inge Friedmann\" width=\"300\" height=\"450\" class=\"alignleft size-full wp-image-8804\" srcset=\"https:\/\/in-the-focus.com\/wp-content\/uploads\/2017\/06\/Inge-Friedmann.jpg 300w, https:\/\/in-the-focus.com\/wp-content\/uploads\/2017\/06\/Inge-Friedmann-200x300.jpg 200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Am Montag, 26.6., um 18:15h (SWR) kommt Inge Friedmann vom Lunzenhof als &#8220;Fohlenmutter&#8221; im Fernsehen. In der Reihe &#8220;Mensch Leute&#8221; erz\u00e4hlen die Filmemacher Geschichten, die sich hinter den Kulissen des scheinbar Allt\u00e4glichen ereignen, so beispielsweise das bange Warten auf den Geburtstermin einer Stute, die vielen Nachtwachen und die Freude, wenn Mutter und Kind wohlauf sind.  Der Lunzenhof im Badischen ist Heimat von Welt-Champion Al Lahab.<br \/>\nWeitere info <a href=\"http:\/\/programm.ard.de\/?sendung=28113146933992\" target=\"_blank\"><strong>hier<\/strong><\/a>!<br \/>\nUnd wer die Sendung am Montag verpasst, hat am 27.6. um 7:50h und 10:20h nochmal eine Chance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Montag, 26.6., um 18:15h (SWR) kommt Inge Friedmann vom Lunzenhof als &#8220;Fohlenmutter&#8221; im Fernsehen. In der Reihe &#8220;Mensch Leute&#8221; erz\u00e4hlen die Filmemacher Geschichten, die sich hinter den Kulissen des scheinbar Allt\u00e4glichen ereignen, so beispielsweise das bange Warten auf den Geburtstermin einer Stute, die vielen Nachtwachen und die Freude, wenn Mutter und Kind wohlauf sind. &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/in-the-focus.com\/en\/2017\/06\/araber-im-fernsehen-die-fohlenmutter\/\">Continue reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":8805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-8803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","item-wrap"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/posts\/8803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/comments?post=8803"}],"version-history":[{"count":2,"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/posts\/8803\/revisions"}],"predecessor-version":[{"id":8807,"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/posts\/8803\/revisions\/8807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/media\/8805"}],"wp:attachment":[{"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/media?parent=8803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/categories?post=8803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/in-the-focus.com\/en\/wp-json\/wp\/v2\/tags?post=8803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}